{"id":7083,"date":"2025-04-21T14:38:01","date_gmt":"2025-04-21T13:38:01","guid":{"rendered":"https:\/\/soussewetter.de\/meteo\/?p=7083"},"modified":"2025-04-21T14:38:49","modified_gmt":"2025-04-21T13:38:49","slug":"niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025","status":"publish","type":"post","link":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/","title":{"rendered":"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025"},"content":{"rendered":"<p style=\"text-align: justify;\">In den vergangenen 24 Stunden zwischen So, 20. April &ndash; Mo, 21. April 2025, 7 Uhr, wurden in sieben von vierundzwanzig Gouvernoraten des Landes teils ergiebige Niederschl&auml;ge registriert. Spitzenreiter waren El Kef im Gouvernorat Kef mit 51 Litern\/m<sup>2<\/sup>, gefolgt von Tabarka im Gouvernorat Jendouba mit 39 Litern\/m<sup>2<\/sup>. Die F&uuml;llstande der Talsperren haben sich etwas verringert.<!--more--><\/p>\n<p><strong>Die wichtigsten registrierten Wetterph&auml;nomene:&nbsp;<\/strong><\/p>\n<p><strong>Hagelschlag im Gouvernorat Kef in:<\/strong>&nbsp;Kef Ville, Kef Boulifa, Sakiet Sidi Youssef, Taj&eacute;rouine, El Ksour, Dahmani, Kalaat Sinan und in den Regionen El Falta und El Hmaima der Delegation von Kalaat Sinan<\/p><div id=\"souss-2821629449\" class=\"souss-inhalt souss-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8074179450971904\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-8074179450971904\" \ndata-ad-slot=\"\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p><strong>Aufgezeichnete Starkwinde in km\/h:<\/strong> Kebili 86, Tozeur 65, begleitet von Sand<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/soussewetter.de\/meteo\/enzyklopaedie\/meteorologie\/niederschlagsmenge\/\" target=\"_blank\" title=\"Die Niederschlagsmenge wird in Millimeter (mm) pro Quadratmeter angegeben. Ein Millimeter Niederschlag pro Quadratmeter entspricht dabei einer Menge von einem Liter Wasser auf einer Fl&auml;che von einem Quadratmeter (Liter\/m2.\" class=\"encyclopedia\">Niederschlagsmenge<\/a>n Tunesien: So, 20. April &ndash; Mo, 21. April 2025, 7 Uhr (alle Angaben in Liter\/m<sup>2<\/sup>)<\/strong><\/p><div id=\"souss-899885076\" class=\"souss-adsense-im-artikel-5 souss-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8074179450971904\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-8074179450971904\" \ndata-ad-slot=\"\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<ul>\n<li style=\"text-align: justify;\"><strong>Ariana:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>B&eacute;ja: <\/strong>Station Oued Ezzargua 15 &ndash; Barrage Sidi Salem 13 &ndash; B&eacute;j&agrave; Sud 23 &ndash; Amdoun 12 &ndash; Tibar 26 &ndash; Barrage Kessab 23 &ndash; Guoubolat 1 &ndash; Mejez El Bab 7 &ndash; Testour 11 &ndash; B&eacute;j&agrave; Station 15 &ndash; Nefza 24 &ndash; Teboursouk 27 &ndash; Makthar Ville 4 &ndash; El Aroussa 6 &ndash; A&iuml;n Bouss&acirc;adia 2 &ndash; G&acirc;afour 13 &ndash; Bargou 2 &ndash; Sidi Bourouis 19 &ndash; Siliana 5 &ndash; Krib 16<\/li>\n<li style=\"text-align: justify;\"><strong>Ben Arous:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Bizert&eacute;:<\/strong> Menzel Bourguiba 5 &ndash; Gh&eacute;zala 8 &ndash; El Azib 1 &ndash; Ras Jebel 1 &ndash; Utique 1 &ndash; Mateur 8 &ndash; Joumine 13 &ndash; Sejn&egrave;ne 18 &ndash; Tinja 7 &ndash; Bizerte 3<\/li>\n<li style=\"text-align: justify;\"><strong>Gab&egrave;s:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Gafsa:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Jendouba: <\/strong>Barrage Bouhertma 24 &ndash; Barrage Barbara 24 &ndash; Balta Bouawan 31 &ndash; Fernana 21 &ndash; Oued Mliz 32 &ndash; B&eacute;ni Mtir 20 &ndash; Ghardimaou 27 &ndash; A&iuml;n Draham 47 &ndash; Boussalem 27 &ndash; Jendouba 21 &ndash; Tabarka 39<\/li>\n<li style=\"text-align: justify;\"><strong>Kairouan: <\/strong>0<\/li>\n<li style=\"text-align: justify;\"><strong>Kasserine: <\/strong>Thala 14 &ndash; Sbeitla 1 &ndash; Hidra 26 &ndash; Kasserine 3 &ndash; Sbiba 3<\/li>\n<li style=\"text-align: justify;\"><strong>Kebili:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Kef: <\/strong>Jrissa 23 &ndash; Touiref 22 &ndash; K13 34 &ndash; Dahmani 31 &ndash; Taj&eacute;rouine 37 &ndash; Kalaat Sinan 26 &ndash; Nebr 28 &ndash; Oued Mall&egrave;gue 38 &ndash; Sers 25 &ndash; Ksour 18 &ndash; Kalaa Khasba 12 &ndash; Sakiet Sidi Youssef 40 &ndash; Kef 51<\/li>\n<li style=\"text-align: justify;\"><strong>Mahdia: <\/strong>0<\/li>\n<li style=\"text-align: justify;\"><strong>Manouba:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>M&eacute;denine (inkl. Djerba):<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Monastir: <\/strong>Teboulba 1 &ndash; Moatmar 1 &ndash; Bembla 2 &ndash; Ksar Helal 2 &ndash; Khniss 1 &ndash; Jamel 1 &ndash; Monastir 1<\/li>\n<li style=\"text-align: justify;\"><strong>Nabeul:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Sfax: <\/strong>0<\/li>\n<li style=\"text-align: justify;\"><strong>Sidi Bouzid:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Siliana: <\/strong>0<\/li>\n<li style=\"text-align: justify;\"><strong>Sousse: <\/strong>0<\/li>\n<li style=\"text-align: justify;\"><strong><strong>Tataouine:<\/strong><\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Tozeur:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Tunis:<\/strong> 0<\/li>\n<li style=\"text-align: justify;\"><strong>Zaghouan:<\/strong> Barrage Oued Kbir 2 &ndash; Barrage Oued Rimal 1 &ndash; A&iuml;n Askar 1 &ndash; Zaghouan 1 &ndash; El Fahs 3<\/li>\n<\/ul>\n<p>Quelle: <a href=\"https:\/\/www.meteo.tn\/fr\/pluviometries\" target=\"_blank\" rel=\"noopener\">INM<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den vergangenen 24 Stunden zwischen So, 20. April \u2013 Mo, 21. April 2025, 7 Uhr, wurden in sieben von<\/p>\n","protected":false},"author":1,"featured_media":7086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[824,308],"tags":[42,8,9,10],"class_list":["post-7083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-statistik-2025","category-wasserversorgung","tag-inm","tag-niederschlagsmengen","tag-niederschlagsstatistik","tag-statistik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025 - Soussewetter.de<\/title>\n<meta name=\"description\" content=\"In den vergangenen 24 Stunden zwischen So, 20. April \u2013 Mo, 21. April 2025, 7 Uhr, wurden in 7 von 24 Gouvernoraten Niederschl\u00e4ge registriert\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025 - Soussewetter.de\" \/>\n<meta property=\"og:description\" content=\"In den vergangenen 24 Stunden zwischen So, 20. April \u2013 Mo, 21. April 2025, 7 Uhr, wurden in 7 von 24 Gouvernoraten Niederschl\u00e4ge registriert\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Soussewetter.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wetterstation.sousse\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-21T13:38:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T13:38:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2025\/04\/800_niederschlag_staudaemme_21042025_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wettermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wettermann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/\"},\"author\":{\"name\":\"Wettermann\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/person\\\/7f913979e47327c0a24925ff22224e12\"},\"headline\":\"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025\",\"datePublished\":\"2025-04-21T13:38:01+00:00\",\"dateModified\":\"2025-04-21T13:38:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/\"},\"wordCount\":267,\"publisher\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/800_niederschlag_staudaemme_21042025_2.jpg\",\"keywords\":[\"INM\",\"Niederschlagsmengen\",\"Niederschlagsstatistik\",\"Statistik\"],\"articleSection\":[\"Statistik 2025\",\"Wasserversorgung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/\",\"name\":\"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025 - Soussewetter.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/800_niederschlag_staudaemme_21042025_2.jpg\",\"datePublished\":\"2025-04-21T13:38:01+00:00\",\"dateModified\":\"2025-04-21T13:38:49+00:00\",\"description\":\"In den vergangenen 24 Stunden zwischen So, 20. April \u2013 Mo, 21. April 2025, 7 Uhr, wurden in 7 von 24 Gouvernoraten Niederschl\u00e4ge registriert\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/800_niederschlag_staudaemme_21042025_2.jpg\",\"contentUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/800_niederschlag_staudaemme_21042025_2.jpg\",\"width\":800,\"height\":445,\"caption\":\"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2025\\\/04\\\/21\\\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Allgemeines\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/category\\\/news\\\/allgemeines\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wasserversorgung\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/category\\\/news\\\/allgemeines\\\/wasserversorgung\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#website\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\",\"name\":\"Soussewetter.de\",\"description\":\"Rund um das Wetter in Tunesien\",\"publisher\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\"},\"alternateName\":\"Wetterstation Akouda\\\/Sousse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\",\"name\":\"Wetterstation Akouda\",\"alternateName\":\"soussewetter.de\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-windmesser_800x332.jpg\",\"contentUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-windmesser_800x332.jpg\",\"width\":512,\"height\":512,\"caption\":\"Wetterstation Akouda\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wetterstation.sousse\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/person\\\/7f913979e47327c0a24925ff22224e12\",\"name\":\"Wettermann\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025 - Soussewetter.de","description":"In den vergangenen 24 Stunden zwischen So, 20. April \u2013 Mo, 21. April 2025, 7 Uhr, wurden in 7 von 24 Gouvernoraten Niederschl\u00e4ge registriert","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/","og_locale":"de_DE","og_type":"article","og_title":"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025 - Soussewetter.de","og_description":"In den vergangenen 24 Stunden zwischen So, 20. April \u2013 Mo, 21. April 2025, 7 Uhr, wurden in 7 von 24 Gouvernoraten Niederschl\u00e4ge registriert","og_url":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/","og_site_name":"Soussewetter.de","article_publisher":"https:\/\/www.facebook.com\/wetterstation.sousse","article_published_time":"2025-04-21T13:38:01+00:00","article_modified_time":"2025-04-21T13:38:49+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2025\/04\/800_niederschlag_staudaemme_21042025_2.jpg","type":"image\/jpeg"}],"author":"Wettermann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Wettermann","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/#article","isPartOf":{"@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/"},"author":{"name":"Wettermann","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/person\/7f913979e47327c0a24925ff22224e12"},"headline":"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025","datePublished":"2025-04-21T13:38:01+00:00","dateModified":"2025-04-21T13:38:49+00:00","mainEntityOfPage":{"@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/"},"wordCount":267,"publisher":{"@id":"https:\/\/soussewetter.de\/meteo\/#organization"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2025\/04\/800_niederschlag_staudaemme_21042025_2.jpg","keywords":["INM","Niederschlagsmengen","Niederschlagsstatistik","Statistik"],"articleSection":["Statistik 2025","Wasserversorgung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/","url":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/","name":"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025 - Soussewetter.de","isPartOf":{"@id":"https:\/\/soussewetter.de\/meteo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/#primaryimage"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2025\/04\/800_niederschlag_staudaemme_21042025_2.jpg","datePublished":"2025-04-21T13:38:01+00:00","dateModified":"2025-04-21T13:38:49+00:00","description":"In den vergangenen 24 Stunden zwischen So, 20. April \u2013 Mo, 21. April 2025, 7 Uhr, wurden in 7 von 24 Gouvernoraten Niederschl\u00e4ge registriert","breadcrumb":{"@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/#primaryimage","url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2025\/04\/800_niederschlag_staudaemme_21042025_2.jpg","contentUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2025\/04\/800_niederschlag_staudaemme_21042025_2.jpg","width":800,"height":445,"caption":"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/soussewetter.de\/meteo\/2025\/04\/21\/niederschlagsmengen-tunesien-so-20-april-mo-21-april-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/soussewetter.de\/meteo\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/soussewetter.de\/meteo\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Allgemeines","item":"https:\/\/soussewetter.de\/meteo\/category\/news\/allgemeines\/"},{"@type":"ListItem","position":4,"name":"Wasserversorgung","item":"https:\/\/soussewetter.de\/meteo\/category\/news\/allgemeines\/wasserversorgung\/"},{"@type":"ListItem","position":5,"name":"Niederschlagsmengen Tunesien: So, 20. April \u2013 Mo, 21. April 2025"}]},{"@type":"WebSite","@id":"https:\/\/soussewetter.de\/meteo\/#website","url":"https:\/\/soussewetter.de\/meteo\/","name":"Soussewetter.de","description":"Rund um das Wetter in Tunesien","publisher":{"@id":"https:\/\/soussewetter.de\/meteo\/#organization"},"alternateName":"Wetterstation Akouda\/Sousse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soussewetter.de\/meteo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/soussewetter.de\/meteo\/#organization","name":"Wetterstation Akouda","alternateName":"soussewetter.de","url":"https:\/\/soussewetter.de\/meteo\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/logo\/image\/","url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/10\/cropped-windmesser_800x332.jpg","contentUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/10\/cropped-windmesser_800x332.jpg","width":512,"height":512,"caption":"Wetterstation Akouda"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wetterstation.sousse"]},{"@type":"Person","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/person\/7f913979e47327c0a24925ff22224e12","name":"Wettermann"}]}},"_links":{"self":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts\/7083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/comments?post=7083"}],"version-history":[{"count":2,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts\/7083\/revisions"}],"predecessor-version":[{"id":7087,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts\/7083\/revisions\/7087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/media\/7086"}],"wp:attachment":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/media?parent=7083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/categories?post=7083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/tags?post=7083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}