{"id":4847,"date":"2023-01-27T15:42:47","date_gmt":"2023-01-27T14:42:47","guid":{"rendered":"https:\/\/soussewetter.de\/meteo\/?p=4847"},"modified":"2023-01-27T15:42:47","modified_gmt":"2023-01-27T14:42:47","slug":"niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr","status":"publish","type":"post","link":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/","title":{"rendered":"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr"},"content":{"rendered":"<p style=\"text-align: justify;\">In den vergangenen 24 Stunden zwischen Donnerstag, den 26 Januar und Freitag, den 27 Januar 2023, 7 Uhr, gab es in elf von vierundzwanzig Gouvernoraten im Norden und Westen des Landes teils ergiebige Niederschl&auml;ge. In den H&ouml;henlagen oberhalb von 800 Metern fielen die Niederschl&auml;ge vielfach als Schnee. Die h&ouml;chsten <a href=\"https:\/\/soussewetter.de\/meteo\/enzyklopaedie\/meteorologie\/niederschlagsmenge\/\" target=\"_blank\" title=\"Die Niederschlagsmenge wird in Millimeter (mm) pro Quadratmeter angegeben. Ein Millimeter Niederschlag pro Quadratmeter entspricht dabei einer Menge von einem Liter Wasser auf einer Fl&auml;che von einem Quadratmeter (Liter\/m2.\" class=\"encyclopedia\">Niederschlagsmenge<\/a>n gab es im Gouvernorat Jendouba mit 7-65 Litern\/m<sup>2<\/sup>, gefolgt von Nabeul mit 1-56 Litern\/m<sup>2<\/sup>.<!--more--><\/p>\n<p><strong>Die Niederschlagsmengen von Do, 26 Jan &ndash; Fr, 27 Jan 2023, 7 Uhr nach Gouvernoraten (alle Angaben in Liter\/m<sup>2<\/sup>)<\/strong><\/p>\n<ul>\n<li>Ariana: 3-6<\/li>\n<li>B&eacute;ja: 2-28<\/li>\n<li>Ben Arous: 1-4<\/li>\n<li>Bizerte: 4-17<\/li>\n<li>Gab&egrave;s:<\/li>\n<li>Gafsa:<\/li>\n<li>Jendouba: 7-65<\/li>\n<li>Kairouan:<\/li>\n<li>Kasserine: 1 (Thala)<\/li>\n<li>K&eacute;bili:<\/li>\n<li>Kef: 1-15<\/li>\n<li>Mahdia:<\/li>\n<li>Manouba: 1-4<\/li>\n<li>M&eacute;denine (inkl. Djerba):<\/li>\n<li>Nabeul: 1-56<\/li>\n<li>Sfax:<\/li>\n<li>Sidi Bouzid:<\/li>\n<li>Siliana:<\/li>\n<li>Sousse:<\/li>\n<li>Tataouine:<\/li>\n<li>Tozeur:<\/li>\n<li>Tunis: 4<\/li>\n<li>Zaghouan: 1-2<\/li>\n<\/ul>\n<p>Quelle &amp; Titelbildgrafik: <a href=\"https:\/\/www.meteo.tn\" target=\"_blank\" rel=\"noopener noreferrer\">INM<\/a><\/p><div id=\"souss-1941945036\" class=\"souss-inhalt souss-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8074179450971904\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-8074179450971904\" \ndata-ad-slot=\"\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>In den vergangenen 24 Stunden zwischen Donnerstag, den 26 Januar und Freitag, den 27 Januar 2023, 7 Uhr, gab es<\/p>\n","protected":false},"author":1,"featured_media":4848,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[574],"tags":[42,8,9,10],"class_list":["post-4847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-statistik-2023","tag-inm","tag-niederschlagsmengen","tag-niederschlagsstatistik","tag-statistik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr - Soussewetter.de<\/title>\n<meta name=\"description\" content=\"In den vergangenen 24 Stunden zwischen Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr, gab es in elf von 24 Gouvernoraten Niederschl\u00e4ge.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr - Soussewetter.de\" \/>\n<meta property=\"og:description\" content=\"In den vergangenen 24 Stunden zwischen Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr, gab es in elf von 24 Gouvernoraten Niederschl\u00e4ge.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/\" \/>\n<meta property=\"og:site_name\" content=\"Soussewetter.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wetterstation.sousse\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T14:42:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2023\/01\/800_niederschlaege_26-27012023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wettermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wettermann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/\"},\"author\":{\"name\":\"Wettermann\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/person\\\/7f913979e47327c0a24925ff22224e12\"},\"headline\":\"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr\",\"datePublished\":\"2023-01-27T14:42:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/\"},\"wordCount\":131,\"publisher\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/800_niederschlaege_26-27012023.jpg\",\"keywords\":[\"INM\",\"Niederschlagsmengen\",\"Niederschlagsstatistik\",\"Statistik\"],\"articleSection\":[\"Statistik 2023\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/\",\"name\":\"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr - Soussewetter.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/800_niederschlaege_26-27012023.jpg\",\"datePublished\":\"2023-01-27T14:42:47+00:00\",\"description\":\"In den vergangenen 24 Stunden zwischen Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr, gab es in elf von 24 Gouvernoraten Niederschl\u00e4ge.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/800_niederschlaege_26-27012023.jpg\",\"contentUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/800_niederschlaege_26-27012023.jpg\",\"width\":800,\"height\":445,\"caption\":\"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2023\\\/01\\\/27\\\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wetter\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/category\\\/news\\\/wetter\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Statistiken\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/category\\\/news\\\/wetter\\\/statistiken\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Statistik 2023\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/category\\\/news\\\/wetter\\\/statistiken\\\/statistik-2023\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#website\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\",\"name\":\"Soussewetter.de\",\"description\":\"Rund um das Wetter in Tunesien\",\"publisher\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\"},\"alternateName\":\"Wetterstation Akouda\\\/Sousse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\",\"name\":\"Wetterstation Akouda\",\"alternateName\":\"soussewetter.de\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-windmesser_800x332.jpg\",\"contentUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-windmesser_800x332.jpg\",\"width\":512,\"height\":512,\"caption\":\"Wetterstation Akouda\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wetterstation.sousse\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/person\\\/7f913979e47327c0a24925ff22224e12\",\"name\":\"Wettermann\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr - Soussewetter.de","description":"In den vergangenen 24 Stunden zwischen Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr, gab es in elf von 24 Gouvernoraten Niederschl\u00e4ge.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/","og_locale":"de_DE","og_type":"article","og_title":"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr - Soussewetter.de","og_description":"In den vergangenen 24 Stunden zwischen Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr, gab es in elf von 24 Gouvernoraten Niederschl\u00e4ge.","og_url":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/","og_site_name":"Soussewetter.de","article_publisher":"https:\/\/www.facebook.com\/wetterstation.sousse","article_published_time":"2023-01-27T14:42:47+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2023\/01\/800_niederschlaege_26-27012023.jpg","type":"image\/jpeg"}],"author":"Wettermann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Wettermann","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/#article","isPartOf":{"@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/"},"author":{"name":"Wettermann","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/person\/7f913979e47327c0a24925ff22224e12"},"headline":"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr","datePublished":"2023-01-27T14:42:47+00:00","mainEntityOfPage":{"@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/"},"wordCount":131,"publisher":{"@id":"https:\/\/soussewetter.de\/meteo\/#organization"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/#primaryimage"},"thumbnailUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2023\/01\/800_niederschlaege_26-27012023.jpg","keywords":["INM","Niederschlagsmengen","Niederschlagsstatistik","Statistik"],"articleSection":["Statistik 2023"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/","url":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/","name":"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr - Soussewetter.de","isPartOf":{"@id":"https:\/\/soussewetter.de\/meteo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/#primaryimage"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/#primaryimage"},"thumbnailUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2023\/01\/800_niederschlaege_26-27012023.jpg","datePublished":"2023-01-27T14:42:47+00:00","description":"In den vergangenen 24 Stunden zwischen Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr, gab es in elf von 24 Gouvernoraten Niederschl\u00e4ge.","breadcrumb":{"@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/#primaryimage","url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2023\/01\/800_niederschlaege_26-27012023.jpg","contentUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2023\/01\/800_niederschlaege_26-27012023.jpg","width":800,"height":445,"caption":"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr"},{"@type":"BreadcrumbList","@id":"https:\/\/soussewetter.de\/meteo\/2023\/01\/27\/niederschlagsmengen-tunesien-do-26-jan-fr-27-jan-2023-7-uhr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/soussewetter.de\/meteo\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/soussewetter.de\/meteo\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Wetter","item":"https:\/\/soussewetter.de\/meteo\/category\/news\/wetter\/"},{"@type":"ListItem","position":4,"name":"Statistiken","item":"https:\/\/soussewetter.de\/meteo\/category\/news\/wetter\/statistiken\/"},{"@type":"ListItem","position":5,"name":"Statistik 2023","item":"https:\/\/soussewetter.de\/meteo\/category\/news\/wetter\/statistiken\/statistik-2023\/"},{"@type":"ListItem","position":6,"name":"Niederschlagsmengen Tunesien: Do, 26 Jan \u2013 Fr, 27 Jan 2023, 7 Uhr"}]},{"@type":"WebSite","@id":"https:\/\/soussewetter.de\/meteo\/#website","url":"https:\/\/soussewetter.de\/meteo\/","name":"Soussewetter.de","description":"Rund um das Wetter in Tunesien","publisher":{"@id":"https:\/\/soussewetter.de\/meteo\/#organization"},"alternateName":"Wetterstation Akouda\/Sousse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soussewetter.de\/meteo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/soussewetter.de\/meteo\/#organization","name":"Wetterstation Akouda","alternateName":"soussewetter.de","url":"https:\/\/soussewetter.de\/meteo\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/logo\/image\/","url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/10\/cropped-windmesser_800x332.jpg","contentUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/10\/cropped-windmesser_800x332.jpg","width":512,"height":512,"caption":"Wetterstation Akouda"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wetterstation.sousse"]},{"@type":"Person","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/person\/7f913979e47327c0a24925ff22224e12","name":"Wettermann"}]}},"_links":{"self":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts\/4847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/comments?post=4847"}],"version-history":[{"count":2,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts\/4847\/revisions"}],"predecessor-version":[{"id":4850,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts\/4847\/revisions\/4850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/media\/4848"}],"wp:attachment":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/media?parent=4847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/categories?post=4847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/tags?post=4847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}