{"id":1341,"date":"2018-12-21T13:10:28","date_gmt":"2018-12-21T12:10:28","guid":{"rendered":"http:\/\/www.soussewetter.de\/meteo\/?p=1341"},"modified":"2018-12-21T13:18:02","modified_gmt":"2018-12-21T12:18:02","slug":"wintersonnenwende-am-freitag-den-21-dezember-2018","status":"publish","type":"post","link":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/","title":{"rendered":"Wintersonnenwende am Freitag, den 21. Dezember 2018"},"content":{"rendered":"<p style=\"text-align: justify;\">In diesem Jahr ist der 21. Dezember 2018 der k&uuml;rzeste Tag des Jahres, die Sonne erreicht die geringste Mittagsh&ouml;he &uuml;ber dem Horizont. Die sogenannte Wintersonnenwende, die in der kommenden Nacht um 23.23 Uhr mitteleurop&auml;ischer Zeit eintritt, markiert auch den astronomischen Winterbeginn. Ab diesem Zeitpunkt werden die Tage wieder l&auml;nger.<!--more--><\/p>\n<p style=\"text-align: justify;\">Grund f&uuml;r die unterschiedliche Verteilung der Jahreszeiten ist die Achsenneigung der Erde von 23,4 Grad. Dadurch bekommt die Erde bei ihrem Umlauf um die Sonne mal im Norden, mal im S&uuml;den mehr Licht ab.<\/p>\n<p style=\"text-align: justify;\">In Akouda bei Sousse geht die Sonne am Freitag um 8.22 Uhr auf und um 17.07 Uhr wieder unter &ndash; eine Tagesl&auml;nge von 9 Stunden und 43 Minuten. Je n&ouml;rdlicher man ist, umso k&uuml;rzer ist der Tag. In der zentralsten Stadt in Deutschland dauert der Freitag nur etwas &uuml;ber 8 Stunden.<\/p><div id=\"souss-1680618835\" class=\"souss-inhalt souss-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8074179450971904\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-8074179450971904\" \ndata-ad-slot=\"\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Daten vom 21.12.2018<\/p>\n<figure id=\"attachment_1344\" aria-describedby=\"caption-attachment-1344\" style=\"width: 782px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/soussewetter.de\/meteo\/astronomie\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1344 size-full\" src=\"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/wintersonnenwende_daten_21122018.jpg\" alt=\"Wintersonnenwende am 21.12.2018 als Daten\" width=\"782\" height=\"509\" srcset=\"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/wintersonnenwende_daten_21122018.jpg 782w, https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/wintersonnenwende_daten_21122018-300x195.jpg 300w, https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/wintersonnenwende_daten_21122018-768x500.jpg 768w\" sizes=\"auto, (max-width: 782px) 100vw, 782px\"><\/a><figcaption id=\"caption-attachment-1344\" class=\"wp-caption-text\">Wintersonnenwende am 21.12.2018 als Daten<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Jahr ist der 21. Dezember 2018 der k\u00fcrzeste Tag des Jahres, die Sonne erreicht die geringste Mittagsh\u00f6he \u00fcber<\/p>\n","protected":false},"author":1,"featured_media":1343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[230],"tags":[242,241,240],"class_list":["post-1341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-astronomie","tag-sonnenwende","tag-winterbeginn","tag-wintersonnenwende"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wintersonnenwende am Freitag, den 21. Dezember 2018 - Soussewetter.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wintersonnenwende am Freitag, den 21. Dezember 2018 - Soussewetter.de\" \/>\n<meta property=\"og:description\" content=\"In diesem Jahr ist der 21. Dezember 2018 der k\u00fcrzeste Tag des Jahres, die Sonne erreicht die geringste Mittagsh\u00f6he \u00fcber\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Soussewetter.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wetterstation.sousse\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-21T12:10:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-21T12:18:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/800_wintersonnenwende.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wettermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wettermann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/\"},\"author\":{\"name\":\"Wettermann\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/person\\\/7f913979e47327c0a24925ff22224e12\"},\"headline\":\"Wintersonnenwende am Freitag, den 21. Dezember 2018\",\"datePublished\":\"2018-12-21T12:10:28+00:00\",\"dateModified\":\"2018-12-21T12:18:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/\"},\"wordCount\":151,\"publisher\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/800_wintersonnenwende.jpg\",\"keywords\":[\"Sonnenwende\",\"Winterbeginn\",\"Wintersonnenwende\"],\"articleSection\":[\"Astronomie\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/\",\"name\":\"Wintersonnenwende am Freitag, den 21. Dezember 2018 - Soussewetter.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/800_wintersonnenwende.jpg\",\"datePublished\":\"2018-12-21T12:10:28+00:00\",\"dateModified\":\"2018-12-21T12:18:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/800_wintersonnenwende.jpg\",\"contentUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/800_wintersonnenwende.jpg\",\"width\":800,\"height\":445,\"caption\":\"Wintersonnenwende\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/2018\\\/12\\\/21\\\/wintersonnenwende-am-freitag-den-21-dezember-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Astronomie\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/category\\\/news\\\/astronomie\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wintersonnenwende am Freitag, den 21. Dezember 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#website\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\",\"name\":\"Soussewetter.de\",\"description\":\"Rund um das Wetter in Tunesien\",\"publisher\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\"},\"alternateName\":\"Wetterstation Akouda\\\/Sousse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\",\"name\":\"Wetterstation Akouda\",\"alternateName\":\"soussewetter.de\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-windmesser_800x332.jpg\",\"contentUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-windmesser_800x332.jpg\",\"width\":512,\"height\":512,\"caption\":\"Wetterstation Akouda\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wetterstation.sousse\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/person\\\/7f913979e47327c0a24925ff22224e12\",\"name\":\"Wettermann\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wintersonnenwende am Freitag, den 21. Dezember 2018 - Soussewetter.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/","og_locale":"de_DE","og_type":"article","og_title":"Wintersonnenwende am Freitag, den 21. Dezember 2018 - Soussewetter.de","og_description":"In diesem Jahr ist der 21. Dezember 2018 der k\u00fcrzeste Tag des Jahres, die Sonne erreicht die geringste Mittagsh\u00f6he \u00fcber","og_url":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/","og_site_name":"Soussewetter.de","article_publisher":"https:\/\/www.facebook.com\/wetterstation.sousse","article_published_time":"2018-12-21T12:10:28+00:00","article_modified_time":"2018-12-21T12:18:02+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/800_wintersonnenwende.jpg","type":"image\/jpeg"}],"author":"Wettermann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Wettermann","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/#article","isPartOf":{"@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/"},"author":{"name":"Wettermann","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/person\/7f913979e47327c0a24925ff22224e12"},"headline":"Wintersonnenwende am Freitag, den 21. Dezember 2018","datePublished":"2018-12-21T12:10:28+00:00","dateModified":"2018-12-21T12:18:02+00:00","mainEntityOfPage":{"@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/"},"wordCount":151,"publisher":{"@id":"https:\/\/soussewetter.de\/meteo\/#organization"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/800_wintersonnenwende.jpg","keywords":["Sonnenwende","Winterbeginn","Wintersonnenwende"],"articleSection":["Astronomie"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/","url":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/","name":"Wintersonnenwende am Freitag, den 21. Dezember 2018 - Soussewetter.de","isPartOf":{"@id":"https:\/\/soussewetter.de\/meteo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/#primaryimage"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/800_wintersonnenwende.jpg","datePublished":"2018-12-21T12:10:28+00:00","dateModified":"2018-12-21T12:18:02+00:00","breadcrumb":{"@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/#primaryimage","url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/800_wintersonnenwende.jpg","contentUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/12\/800_wintersonnenwende.jpg","width":800,"height":445,"caption":"Wintersonnenwende"},{"@type":"BreadcrumbList","@id":"https:\/\/soussewetter.de\/meteo\/2018\/12\/21\/wintersonnenwende-am-freitag-den-21-dezember-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/soussewetter.de\/meteo\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/soussewetter.de\/meteo\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Astronomie","item":"https:\/\/soussewetter.de\/meteo\/category\/news\/astronomie\/"},{"@type":"ListItem","position":4,"name":"Wintersonnenwende am Freitag, den 21. Dezember 2018"}]},{"@type":"WebSite","@id":"https:\/\/soussewetter.de\/meteo\/#website","url":"https:\/\/soussewetter.de\/meteo\/","name":"Soussewetter.de","description":"Rund um das Wetter in Tunesien","publisher":{"@id":"https:\/\/soussewetter.de\/meteo\/#organization"},"alternateName":"Wetterstation Akouda\/Sousse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soussewetter.de\/meteo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/soussewetter.de\/meteo\/#organization","name":"Wetterstation Akouda","alternateName":"soussewetter.de","url":"https:\/\/soussewetter.de\/meteo\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/logo\/image\/","url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/10\/cropped-windmesser_800x332.jpg","contentUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/10\/cropped-windmesser_800x332.jpg","width":512,"height":512,"caption":"Wetterstation Akouda"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wetterstation.sousse"]},{"@type":"Person","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/person\/7f913979e47327c0a24925ff22224e12","name":"Wettermann"}]}},"_links":{"self":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts\/1341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/comments?post=1341"}],"version-history":[{"count":5,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts\/1341\/revisions"}],"predecessor-version":[{"id":1348,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/posts\/1341\/revisions\/1348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/media\/1343"}],"wp:attachment":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/media?parent=1341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/categories?post=1341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/tags?post=1341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}