{"id":6130,"date":"2024-05-28T13:17:35","date_gmt":"2024-05-28T12:17:35","guid":{"rendered":"https:\/\/soussewetter.de\/meteo\/?post_type=encyclopedia&#038;p=6130"},"modified":"2024-05-28T13:17:35","modified_gmt":"2024-05-28T12:17:35","slug":"strasse-von-sizilien","status":"publish","type":"encyclopedia","link":"https:\/\/soussewetter.de\/meteo\/enzyklopaedie\/geologie\/strasse-von-sizilien\/","title":{"rendered":"Stra\u00dfe von Sizilien"},"content":{"rendered":"<p style=\"text-align: justify;\">Die Stra&szlig;e von Sizilien bezeichnet eine Meerenge beziehungsweise Meeresregion des Mittelmeeres zwischen Sizilien und Tunesien. Sie verbindet das &ouml;stliche Becken mit dem westlichen Becken des Mittelmeeres. An ihrer engsten Stelle hat die Stra&szlig;e von Sizilien eine Breite von etwa 145 km.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","encyclopedia-category":[731],"encyclopedia-tag":[733,668,732],"class_list":["post-6130","encyclopedia","type-encyclopedia","status-publish","hentry","encyclopedia-category-geologie","encyclopedia-tag-meeresenge","encyclopedia-tag-mittelmeer","encyclopedia-tag-strasse-von-sizilien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stra\u00dfe von Sizilien - Soussewetter.de<\/title>\n<meta name=\"description\" content=\"Die Stra\u00dfe von Sizilien bezeichnet eine Meerenge beziehungsweise Meeresregion des Mittelmeeres zwischen Sizilien und Tunesien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soussewetter.de\/meteo\/glossar\/geologie\/strasse-von-sizilien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stra\u00dfe von Sizilien - Soussewetter.de\" \/>\n<meta property=\"og:description\" content=\"Die Stra\u00dfe von Sizilien bezeichnet eine Meerenge beziehungsweise Meeresregion des Mittelmeeres zwischen Sizilien und Tunesien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soussewetter.de\/meteo\/glossar\/geologie\/strasse-von-sizilien\/\" \/>\n<meta property=\"og:site_name\" content=\"Soussewetter.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wetterstation.sousse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/glossar\\\/geologie\\\/strasse-von-sizilien\\\/\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/glossar\\\/geologie\\\/strasse-von-sizilien\\\/\",\"name\":\"Stra\u00dfe von Sizilien - Soussewetter.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#website\"},\"datePublished\":\"2024-05-28T12:17:35+00:00\",\"description\":\"Die Stra\u00dfe von Sizilien bezeichnet eine Meerenge beziehungsweise Meeresregion des Mittelmeeres zwischen Sizilien und Tunesien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/glossar\\\/geologie\\\/strasse-von-sizilien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/glossar\\\/geologie\\\/strasse-von-sizilien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/glossar\\\/geologie\\\/strasse-von-sizilien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enzyklop\u00e4die\",\"item\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/enzyklopaedie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stra\u00dfe von Sizilien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#website\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\",\"name\":\"Soussewetter.de\",\"description\":\"Rund um das Wetter in Tunesien\",\"publisher\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\"},\"alternateName\":\"Wetterstation Akouda\\\/Sousse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#organization\",\"name\":\"Wetterstation Akouda\",\"alternateName\":\"soussewetter.de\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-windmesser_800x332.jpg\",\"contentUrl\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-windmesser_800x332.jpg\",\"width\":512,\"height\":512,\"caption\":\"Wetterstation Akouda\"},\"image\":{\"@id\":\"https:\\\/\\\/soussewetter.de\\\/meteo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wetterstation.sousse\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stra\u00dfe von Sizilien - Soussewetter.de","description":"Die Stra\u00dfe von Sizilien bezeichnet eine Meerenge beziehungsweise Meeresregion des Mittelmeeres zwischen Sizilien und Tunesien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soussewetter.de\/meteo\/glossar\/geologie\/strasse-von-sizilien\/","og_locale":"de_DE","og_type":"article","og_title":"Stra\u00dfe von Sizilien - Soussewetter.de","og_description":"Die Stra\u00dfe von Sizilien bezeichnet eine Meerenge beziehungsweise Meeresregion des Mittelmeeres zwischen Sizilien und Tunesien.","og_url":"https:\/\/soussewetter.de\/meteo\/glossar\/geologie\/strasse-von-sizilien\/","og_site_name":"Soussewetter.de","article_publisher":"https:\/\/www.facebook.com\/wetterstation.sousse","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soussewetter.de\/meteo\/glossar\/geologie\/strasse-von-sizilien\/","url":"https:\/\/soussewetter.de\/meteo\/glossar\/geologie\/strasse-von-sizilien\/","name":"Stra\u00dfe von Sizilien - Soussewetter.de","isPartOf":{"@id":"https:\/\/soussewetter.de\/meteo\/#website"},"datePublished":"2024-05-28T12:17:35+00:00","description":"Die Stra\u00dfe von Sizilien bezeichnet eine Meerenge beziehungsweise Meeresregion des Mittelmeeres zwischen Sizilien und Tunesien.","breadcrumb":{"@id":"https:\/\/soussewetter.de\/meteo\/glossar\/geologie\/strasse-von-sizilien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soussewetter.de\/meteo\/glossar\/geologie\/strasse-von-sizilien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soussewetter.de\/meteo\/glossar\/geologie\/strasse-von-sizilien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/soussewetter.de\/meteo\/"},{"@type":"ListItem","position":2,"name":"Enzyklop\u00e4die","item":"https:\/\/soussewetter.de\/meteo\/enzyklopaedie\/"},{"@type":"ListItem","position":3,"name":"Stra\u00dfe von Sizilien"}]},{"@type":"WebSite","@id":"https:\/\/soussewetter.de\/meteo\/#website","url":"https:\/\/soussewetter.de\/meteo\/","name":"Soussewetter.de","description":"Rund um das Wetter in Tunesien","publisher":{"@id":"https:\/\/soussewetter.de\/meteo\/#organization"},"alternateName":"Wetterstation Akouda\/Sousse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soussewetter.de\/meteo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/soussewetter.de\/meteo\/#organization","name":"Wetterstation Akouda","alternateName":"soussewetter.de","url":"https:\/\/soussewetter.de\/meteo\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/logo\/image\/","url":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/10\/cropped-windmesser_800x332.jpg","contentUrl":"https:\/\/soussewetter.de\/meteo\/wp-content\/uploads\/2018\/10\/cropped-windmesser_800x332.jpg","width":512,"height":512,"caption":"Wetterstation Akouda"},"image":{"@id":"https:\/\/soussewetter.de\/meteo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wetterstation.sousse"]}]}},"_links":{"self":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/encyclopedia\/6130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/encyclopedia"}],"about":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/types\/encyclopedia"}],"author":[{"embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/encyclopedia\/6130\/revisions"}],"predecessor-version":[{"id":6131,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/encyclopedia\/6130\/revisions\/6131"}],"wp:attachment":[{"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/media?parent=6130"}],"wp:term":[{"taxonomy":"encyclopedia-category","embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/encyclopedia-category?post=6130"},{"taxonomy":"encyclopedia-tag","embeddable":true,"href":"https:\/\/soussewetter.de\/meteo\/wp-json\/wp\/v2\/encyclopedia-tag?post=6130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}